{"id":28151,"date":"2018-06-20T14:31:23","date_gmt":"2018-06-20T12:31:23","guid":{"rendered":"https:\/\/libmod.de\/?p=28151"},"modified":"2020-03-28T02:21:13","modified_gmt":"2020-03-28T01:21:13","slug":"margareta-mommsen-wm2018-russland-verstehen-putins-politbuero","status":"publish","type":"post","link":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/","title":{"rendered":"Putins Polit\u00adb\u00fcro (1\/\u200b3)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<figure id=\"attachment_28092\" aria-describedby=\"caption-attachment-28092\" style=\"width: 1199px\" class=\"wp-caption alignnone\"><img class=\"wp-image-28092 \" src=\"https:\/\/libmod.de\/wp-content\/uploads\/Putins-Politb\u00fcro-I-770x321.jpg\" alt width=\"1199\" height=\"500\"><figcaption id=\"caption-attachment-28092\" class=\"wp-caption-text\">Quelle: kremlin.ru<\/figcaption><\/figure>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u201c.vc_custom_1508251598805{margin-top: 30px !important;}\u201c][vc_column width=\u201e2\/3\u201c css=\u201c.vc_custom_1508252250311{padding-right: 20px !important;}\u201c][vc_column_text]<\/p>\n<h2><a href=\"https:\/\/libmod.de\/dossier-fussball-weltmeisterschaft-2018-russland-verstehen\/\">WM-Dossier\u201c Russ\u00adland ver\u00adste\u00adhen\u201c<\/a>: In einem Drei\u00adtei\u00adler spannt die Poli\u00adtik\u00adwis\u00adsen\u00adschaft\u00adle\u00adrin Mar\u00adga\u00adreta Mommsen den Bogen vom Ende der Sowjet\u00adunion hin zum \u201ePutin Syn\u00addi\u00adkat\u201c. Im ersten Teil zeigt sie, wie der schil\u00adlernde Mythos um den rus\u00adsi\u00adschen Pr\u00e4\u00adsi\u00adden\u00adten die Macht\u00adver\u00adh\u00e4lt\u00adnisse im Land ver\u00adschlei\u00adert. Tat\u00ads\u00e4ch\u00adlich wird das WM-Gast\u00adge\u00adber\u00adland von einem klan\u00addes\u00adti\u00adnen Netz\u00adwerk aus Indus\u00adtrie\u00adbos\u00adsen und Olig\u00adar\u00adchen regiert \u2013 Putins&nbsp;Politb\u00fcro.<\/h2>\n<p><!--more--><\/p>\n<p>Als Wla\u00addi\u00admir Putin im M\u00e4rz zum vierten Mal zum Pr\u00e4\u00adsi\u00adden\u00adten gew\u00e4hlt wurde, holte er mit 76,7 Prozent der Stimmen sein bestes Ergeb\u00adnis. Doch der kom\u00adfor\u00adta\u00adble Wahl\u00adsieg t\u00e4uscht. Obwohl Wahl\u00adaus\u00adgang und Wahl\u00adbe\u00adtei\u00adli\u00adgung die vom Kreml anvi\u00adsier\u00adten Ziel\u00admar\u00adken erreichte, waren Putin und seine Berater in den Wochen zuvor durch\u00adaus&nbsp;nerv\u00f6s.<\/p>\n<blockquote><p>Russ\u00adland ist ein Schat\u00adten\u00adreich aus kri\u00admi\u00adnel\u00adlen und halb\u00adle\u00adga\u00adlen unter\u00adneh\u00adme\u00adri\u00adschen&nbsp;Interessen<\/p><\/blockquote>\n<p>Denn ein Sieg allein reichte nicht. Die Wahl musste ein ful\u00admi\u00adnan\u00adtes Ergeb\u00adnis her\u00advor\u00adbrin\u00adgen, das dem hohen Legi\u00adti\u00admi\u00adt\u00e4ts\u00adan\u00adspruch des als unan\u00adge\u00adfoch\u00adten gel\u00adten\u00adden Pr\u00e4\u00adsi\u00adden\u00adten ent\u00adspricht. Darum bangte der F\u00fch\u00adrungs\u00adzir\u00adkel um Putin bis zuletzt. Er f\u00fcrch\u00adtete, dass die Oppo\u00adsi\u00adtion ihre poli\u00adti\u00adsierte W\u00e4h\u00adler\u00adschaft nahezu voll\u00adst\u00e4n\u00addig mobi\u00adli\u00adsie\u00adren k\u00f6nnte. Der popu\u00adl\u00e4rste Putin-Kri\u00adti\u00adker, Alexej Nawalny, hatte zum Wahl\u00adboy\u00adkott auf\u00adge\u00adru\u00adfen. Ob dem Kreml eine breite Mobi\u00adli\u00adsie\u00adrung gel\u00e4nge, war&nbsp;offen.<\/p>\n<p>In den Tagen vor der Wahl stieg das Inter\u00adesse der W\u00e4hler pl\u00f6tz\u00adlich sprung\u00adhaft an. Ella Pam\u00adfi\u00adlowa, die Lei\u00adte\u00adrin der Zen\u00adtra\u00adlen Wahl\u00adkom\u00admis\u00adsion, erkl\u00e4rte im Nach\u00adhin\u00adein frei\u00adm\u00fc\u00adtig, dass der Grund die Salven der Kritik aus west\u00adli\u00adchen Haupt\u00adst\u00e4d\u00adten nach dem Gift\u00adan\u00adschlag auf Sergej Skripal gewesen seien. Der Fall Skripal und seine Aus\u00adwir\u00adkung auf die Pr\u00e4\u00adsi\u00addent\u00adschafts\u00adwahl zeigt exem\u00adpla\u00adrisch, wie Putin durch eine kon\u00adfron\u00adta\u00adtive Au\u00dfen\u00adpo\u00adli\u00adtik W\u00e4hler an die Urnen&nbsp;bewegt.&nbsp;<\/p><div class=\"libmod-author-box\"><p><img src=\"https:\/\/libmod.de\/wp-content\/uploads\/mommsen_rund.jpg\" alt=\"Portrait von Margareta Mommsen\"><\/p><p><a href=\"https:\/\/libmod.de\/author\/margareta-mommsen\/\">Mar\u00adga\u00adreta Mommsen<\/a> ist eme\u00adri\u00adtierte Pro\u00adfes\u00adso\u00adrin f\u00fcr Poli\u00adtik\u00adwis\u00adsen\u00adschaft an der Ludwig-Maxi\u00admi\u00adli\u00adans-Uni\u00adver\u00adsi\u00adt\u00e4t&nbsp;M\u00fcnchen<\/p>\n<\/div>\n<h2>Der Mythos&nbsp;Putin<\/h2>\n<p>Zwar lenken auch andere Staaten auf diese Weise von Krisen im Inneren ab (Russ\u00adlands Wirt\u00adschaft ist marode und global alles andere als wett\u00adbe\u00adwerbs\u00adf\u00e4\u00adhig), doch es gibt wohl keine Schein\u00adde\u00admo\u00adkra\u00adtie, die derart wir\u00adkungs\u00advoll \u2013 man m\u00f6chte fast sagen \u201epro\u00adfes\u00adsio\u00adnell\u201c \u2013 gelenkt wird, wie Putins Russ\u00adland. Nur auf dem Papier sind Kan\u00addi\u00adda\u00adten f\u00fcr das Pr\u00e4\u00adsi\u00adden\u00adten\u00adamt chan\u00adcen\u00adgleich. In Wirk\u00adlich\u00adkeit pro\u00adfi\u00adtiert Putin von einer die \u00d6ffent\u00adlich\u00adkeit aus\u00adf\u00fcl\u00adlen\u00adden Staats\u00adpro\u00adpa\u00adganda, weshalb er in die Nie\u00adde\u00adrun\u00adgen eines offenen Wahl\u00adkampfs nicht abzu\u00adstei\u00adgen&nbsp;braucht.<\/p>\n<p>Gegen\u00adw\u00e4r\u00adtig wird Russ\u00adland durch nichts anderes zusam\u00admen\u00adge\u00adhal\u00adten als den \u201eMythos Putin\u201c. Er speist sich aus der plan\u00advol\u00adlen Insze\u00adnie\u00adrung Putins als Wel\u00adten\u00adlen\u00adker, der angeb\u00adli\u00adche Feind\u00adse\u00adlig\u00adkei\u00adten des Westens mit Bravour pariert. Bereits seine erste Wie\u00adder\u00adwahl im Jahr 2004 plant Putins Bera\u00adter\u00adstab als ein Best\u00e4\u00adti\u00adgungs\u00adre\u00adfe\u00adren\u00addum, als eine Feier der Tap\u00adfer\u00adkeit und Geris\u00adsen\u00adheit des rus\u00adsi\u00adschen Pr\u00e4\u00adsi\u00adden\u00adten, wie sich der dama\u00adlige Poli\u00adtik\u00adbe\u00adra\u00adter des Kremls, Gleb Paw\u00adlow\u00adski erin\u00adnert: Die Polit\u00adtech\u00adno\u00adlo\u00adgen h\u00e4tten eine derart anste\u00adckende \u201eStim\u00admung der Sta\u00adbi\u00adli\u00adt\u00e4t und des Tri\u00adumphs\u201c ent\u00adfacht, weshalb es ihnen \u00fcber\u00adfl\u00fcs\u00adsig erschien, Plu\u00adra\u00adlis\u00admus auch nur vorzut\u00e4uschen.<\/p>\n<p>Der Mythos vom Wel\u00adten\u00adlen\u00adker wird in den Fol\u00adge\u00adjah\u00adren auf die Spitze getrie\u00adben. Nach der als \u201eHeim\u00adho\u00adlung\u201c gefei\u00ader\u00adten Anne\u00adxion der Krim sti\u00adli\u00adsie\u00adren die Pro\u00adpa\u00adgan\u00addis\u00adten Putin zum Inbe\u00adgriff Russ\u00adlands natio\u00adna\u00adler Iden\u00adti\u00adt\u00e4t. Der stell\u00adver\u00adtre\u00adtende Leiter der Pr\u00e4\u00adsi\u00addi\u00adal\u00adver\u00adwal\u00adtung, Wjat\u00adsches\u00adlaw Wolodin, gibt die Devise aus: \u201ePutin ist Russ\u00adland und ohne Putin ist Russ\u00adland&nbsp;nichts.\u201c<\/p>\n<h2>Das Putin-Syn\u00addi\u00adkat<\/h2>\n<p>Doch der Putin-Kult ver\u00adschlei\u00adert die wahren Macht\u00adver\u00adh\u00e4lt\u00adnisse in Russ\u00adland. Ent\u00adge\u00adgen dem Ein\u00addruck, den die Kreml-Pro\u00adpa\u00adganda erzeugt, regiert hinter Putin eine klan\u00addes\u00adtine Olig\u00adar\u00adchie aus Indus\u00adtrie\u00adbos\u00adsen und Geheim\u00addienst\u00adof\u00adfi\u00adzie\u00adren: Das <a href=\"https:\/\/www.chbeck.de\/mommsen-putin-syndikat\/product\/20344005\">Putin-Syn\u00addi\u00adkat<\/a>. Man k\u00f6nnte das Syn\u00addi\u00adkat auch das wie\u00adder\u00adauf\u00ader\u00adstan\u00addene Polit\u00adb\u00fcro nennen und Putin seinen Ersten&nbsp;Sekret\u00e4r.<\/p>\n<p>Um Putins Russ\u00adland zu ver\u00adste\u00adhen, muss man ein Miss\u00adver\u00adst\u00e4nd\u00adnis kl\u00e4ren: Russ\u00adland ist kein mono\u00adli\u00adthi\u00adscher Auto\u00adri\u00adta\u00adris\u00admus. Es ist ein Schat\u00adten\u00adreich aus kri\u00admi\u00adnel\u00adlen und halb\u00adle\u00adga\u00adlen unter\u00adneh\u00adme\u00adri\u00adschen Inter\u00ades\u00adsen, die von Putin allen\u00adfalls mode\u00adriert werden. \u00dcber die Dynamik des Wett\u00adbe\u00adwerbs von Hoch\u00adb\u00fc\u00adro\u00adkra\u00adtie und Gro\u00df\u00adin\u00addus\u00adtrie, der in der Regel im Ver\u00adbor\u00adge\u00adnen statt\u00adfin\u00addet, dringen nur selten Infor\u00adma\u00adtio\u00adnen an die \u00d6ffentlichkeit.<\/p>\n<p>Meis\u00adtens wird das Hauen und Stechen in Wirt\u00adschafts\u00adkon\u00adflik\u00adten sicht\u00adbar. J\u00fcngs\u00adtes Bei\u00adspiel ist das Drama um den ehe\u00adma\u00adli\u00adgen Minis\u00adter f\u00fcr Wirt\u00adschafts\u00adent\u00adwick\u00adlung, Aleksej Uljuka\u00adjew, der wegen Bestechungs\u00advor\u00adw\u00fcr\u00adfen ver\u00adhaf\u00adtet und zu acht Jahren Straf\u00adla\u00adger ver\u00adur\u00adteilt worden ist. Hin\u00adter\u00adgrund soll ein Ver\u00adtei\u00adlungs\u00adkon\u00adflikt in der \u00d6lin\u00addus\u00adtrie sein. Putins lang\u00adj\u00e4h\u00adri\u00adger Ver\u00adtrau\u00adter Igor Set\u00adschin, der Vor\u00adstands\u00advor\u00adsit\u00adzende von Rosneft, scheint aber\u00admals seine Inter\u00ades\u00adsen gegen einen Wider\u00adsa\u00adcher durch\u00adge\u00adsetzt zu&nbsp;haben.<\/p>\n<h2>Russ\u00adlands demo\u00adkra\u00adti\u00adsche Trans\u00adfor\u00adma\u00adtion ist gescheitert<\/h2>\n<p>Putins Russ\u00adland wird von der Pro\u00adpa\u00adganda eines F\u00fch\u00adrer\u00adstaa\u00adtes zusam\u00admen\u00adge\u00adhal\u00adten und einer nichts als dem Geld ver\u00adpflich\u00adte\u00adten Olig\u00adar\u00adchie regiert. Auch wenn in Russ\u00adland Wahlen abge\u00adhal\u00adten werden \u2013 demo\u00adkra\u00adtisch regiert wird das Land nicht. Anders als in anderen post\u00adkom\u00admu\u00adnis\u00adti\u00adschen Staaten \u2013 etwa Estland, Lett\u00adland und Litauen \u2013 ist die Trans\u00adfor\u00adma\u00adtion eines kom\u00admu\u00adnis\u00adti\u00adschen Staates in eine libe\u00adrale Demo\u00adkra\u00adtie in Russ\u00adland gescheitert.<\/p>\n<p><em>Im n\u00e4chs\u00adten Beitrag erkl\u00e4rt Mar\u00adga\u00adreta Mommsen, warum in Russ\u00adland das demo\u00adkra\u00adti\u00adsche Expe\u00adri\u00adment vorerst geschei\u00adtert ist. Von ihr erschien im Verlag C.H. Beck \u201e<a href=\"https:\/\/www.chbeck.de\/mommsen-putin-syndikat\/product\/20344005\">Das Putin Syn\u00addi\u00adkat \u2013 Russ\u00adland im Griff der Geheim\u00addienst\u00adler<\/a>\u201c (2017).<br>\n<\/em><\/p>\n<p><img class=\"alignnone wp-image-23921 size-full\" src=\"https:\/\/russlandverstehen.eu\/wp-content\/uploads\/textende.png\" alt=\"Textende\" width=\"40\" height=\"120\">[\/vc_column_text][\/vc_column][vc_column width=\u201e1\/3\u201c el_class=\u201edimmer\u201c][vc_empty_space height=\u201e130px\u201c][vc_column_text]<\/p>\n<h2>Ver\u00adwandte&nbsp;Themen<\/h2>\n<p>[\/vc_column_text][vc_basic_grid post_type=\u201epost\u201c max_items=\u201e3\u201c element_width=\u201e12\u201c item=\u201e24066\u201c grid_id=\u201evc_gid:1529517313762\u201399c6a7cc-fe4d\u20111\u201c css=\u201c.vc_custom_1508761943581{background-color: #ffffff !important;}\u201c taxonomies=\u201e51\u201c][vc_row_inner css=\u201c.vc_custom_1508164629489{margin-top: 30px !important;margin-right: 0px !important;margin-left: 0px !important;background-color: #03d0b6 !important;}\u201c][vc_column_inner][vc_column_text css=\u201c.vc_custom_1508167210959{margin-top: \u201115px !important;}\u201c]<\/p>\n<h2><span style=\"color: #ffffff;\">News\u00adlet\u00adter&nbsp;bestellen<\/span><\/h2>\n<p>[\/vc_column_text][vc_column_text css=\u201c.vc_custom_1508166779270{margin-top: \u201110px !important;}\u201c]Mit dem LibMod-News\u00adlet\u00adter erhal\u00adten Sie regel\u00adm\u00e4\u00ad\u00dfig Neu\u00adig\u00adkei\u00adten zu unseren Themen in Ihr&nbsp;Postfach.<\/p>\n<p><script>(function() {\n\twindow.mc4wp = window.mc4wp || {\n\t\tlisteners: [],\n\t\tforms: {\n\t\t\ton: function(evt, cb) {\n\t\t\t\twindow.mc4wp.listeners.push(\n\t\t\t\t\t{\n\t\t\t\t\t\tevent   : evt,\n\t\t\t\t\t\tcallback: cb\n\t\t\t\t\t}\n\t\t\t\t);\n\t\t\t}\n\t\t}\n\t}\n})();\n<\/script><!-- Mailchimp for WordPress v4.14.0 - https:\/\/wordpress.org\/plugins\/mailchimp-for-wp\/ --><\/p><form id=\"mc4wp-form-1\" class=\"mc4wp-form mc4wp-form-24179 mc4wp-form-theme mc4wp-form-theme-light\" method=\"post\" data-id=\"24179\" data-name=\"LibMod Newsletter\"><div class=\"mc4wp-form-fields\"><h3 style=\"margin: 0;\"><span style=\"color: #ffffff;\">News\u00adlet\u00adter&nbsp;bestellen<\/span><\/h3>\n  <br><p>\n    <label>Anrede \u2002\u2002\u2002 \u2002<\/label>\n \n      <select id=\"MMERGE7\" name=\"MMERGE7\" required>\n            <option value=\"Frau\">Frau<\/option>\n            <option value=\"Herr\">Herr<\/option>\n        <option value=\"X\">X<\/option>\n    <\/select>\n<\/p>\n \n<input type=\"hidden\" id=\"MMERGE8\" name=\"MMERGE8\" value>\n \n<input type=\"hidden\" name=\"INTERESTS[da6787e670][]\" value=\"add396f6be\"> \n \n<p><label>Vorname\u2002\u2002 \u2002<\/label>\n    <input type=\"text\" name=\"FNAME\" required>\n<\/p>\n<p>\n<label>Nach\u00adname\u2002\u2002<\/label>\n    <input type=\"text\" name=\"LNAME\" required>\n<\/p>\n<p>\n<label>Insti\u00adtu\u00adtion \u2002\u2002<\/label>\n    <input type=\"text\" name=\"MMERGE10\">\n<\/p>\n \n<p>\n            <label for=\"email\">E\u2011Mail-Adresse<\/label>\n                        <input type=\"email\" id=\"email\" name=\"EMAIL\" placeholder=\"Deine E-Mail-Adresse\" autocomplete=\"email\" required>\n<\/p>\n \n<p>Mit unseren <span style=\"color: #000000;\"><a style=\"color: #ffffff;\" href=\"https:\/\/libmod.de\/datenschutzerklaerung\/\" target=\"_blank\" rel=\"noopener\">Daten\u00adschutz\u00adbe\u00adstim\u00admun\u00adgen<\/a><\/span> erkl\u00e4\u00adren Sie sich einverstanden.<\/p>\n \n \n<p>\n            <input type=\"submit\" value=\"Absenden\">\n<\/p>\n \n<script>\n  document.addEventListener('DOMContentLoaded', function () {\n    const anrede = document.getElementById('MMERGE7');\n    const liebelieber = document.getElementById('MMERGE8');\n   \n    function updateliebelieber() {\n      if (anrede.value === 'Herr') {\n        liebelieber.value = 'Lieber';\n      } else if (anrede.value === 'Frau') {\n        liebelieber.value = 'Liebe';\n      } else if (anrede.value === 'X') {\n        liebelieber.value = 'Hallo';\n      } else {\n        liebelieber.value = '';\n      }\n    }\n   \n    anrede.addEventListener('change', updateliebelieber);\n    updateliebelieber();\n  });\n<\/script><\/div><label style=\"display: none !important;\">Wenn du ein Mensch bist, lasse das Feld&nbsp;leer:&nbsp;<input type=\"text\" name=\"_mc4wp_honeypot\" value tabindex=\"-1\" autocomplete=\"off\"><\/label><input type=\"hidden\" name=\"_mc4wp_timestamp\" value=\"1788350330\"><input type=\"hidden\" name=\"_mc4wp_form_id\" value=\"24179\"><input type=\"hidden\" name=\"_mc4wp_form_element_id\" value=\"mc4wp-form-1\"><div class=\"mc4wp-response\"><\/div><\/form><!-- \/ Mailchimp for WordPress Plugin -->[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] [\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u201c.vc_custom_1508251598805{margin-top: 30px !important;}\u201c][vc_column width=\u201e2\/3\u201c css=\u201c.vc_custom_1508252250311{padding-right: 20px !important;}\u201c][vc_column_text] WM-Dossier\u201c Russ\u00adland ver\u00adste\u00adhen\u201c: In einem Drei\u00adtei\u00adler spannt die Poli\u00adtik\u00adwis\u00adsen\u00adschaft\u00adle\u00adrin Mar\u00adga\u00adreta Mommsen den Bogen vom Ende der Sowjet\u00adunion hin zum \u201ePutin&nbsp;Syndikat\u201c....<\/p>\n","protected":false},"author":69,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[20],"tags":[48,79,30,4007],"class_list":["post-28151","post","type-post","status-publish","format-standard","category-analyse","tag-oestliche-nachbarschaft","tag-putin","tag-russland","tag-wm2018"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Russland verstehen: Putins Polit\u00adb\u00fcro (1\/\u200b3)<\/title>\n<meta name=\"description\" content=\"Im ersten Teil zeigt Margareta Mommsen, wie der schil\u00adlernde Mythos um den rus\u00adsi\u00adschen Pr\u00e4\u00adsi\u00adden\u00adten die Macht\u00adver\u00adh\u00e4lt\u00adnisse im Land ver\u00adschlei\u00adert. Tat\u00ads\u00e4ch\u00adlich wird das WM-Gast\u00adge\u00adber\u00adland von einem klan\u00addes\u00adti\u00adnen Netz\u00adwerk aus Indus\u00adtrie\u00adbos\u00adsen und Olig\u00adar\u00adchen regiert \u2013 Putins Polit\u00adb\u00fcro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Putins Polit\u00adb\u00fcro (1\/\u200b3)\" \/>\n<meta property=\"og:description\" content=\"Der schillernde Mythos um Wladimir Putin verschleiert die wahren Machtverh\u00e4ltnisse im Land.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/\" \/>\n<meta property=\"og:site_name\" content=\"Russland verstehen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiberaleModerne\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-20T12:31:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-28T01:21:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/russlandverstehen.eu\/wp-content\/uploads\/textende.png\" \/>\n<meta name=\"author\" content=\"Margareta Mommsen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Putins Polit\u00adb\u00fcro (1\/\u200b3)\" \/>\n<meta name=\"twitter:description\" content=\"Der schillernde Mythos um Wladimir Putin verschleiert die wahren Machtverh\u00e4ltnisse im Land\" \/>\n<meta name=\"twitter:creator\" content=\"@liberalemoderne\" \/>\n<meta name=\"twitter:site\" content=\"@liberalemoderne\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Margareta Mommsen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/\"},\"author\":{\"name\":\"Margareta Mommsen\",\"@id\":\"\\\/#\\\/schema\\\/person\\\/a0d0021b49707475f3a72175f498f52e\"},\"headline\":\"Putins Polit\u00adb\u00fcro (1\\\/\u200b3)\",\"datePublished\":\"2018-06-20T12:31:23+00:00\",\"dateModified\":\"2020-03-28T01:21:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/\"},\"wordCount\":947,\"publisher\":{\"@id\":\"\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/russlandverstehen.eu\\\/wp-content\\\/uploads\\\/textende.png\",\"keywords\":[\"\u00d6stliche Nachbarschaft\",\"Putin\",\"Russland\",\"WM2018\"],\"articleSection\":[\"Analyse&emsp;\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/\",\"url\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/\",\"name\":\"Russland verstehen: Putins Polit\u00adb\u00fcro (1\\\/\u200b3)\",\"isPartOf\":{\"@id\":\"\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/russlandverstehen.eu\\\/wp-content\\\/uploads\\\/textende.png\",\"datePublished\":\"2018-06-20T12:31:23+00:00\",\"dateModified\":\"2020-03-28T01:21:13+00:00\",\"description\":\"Im ersten Teil zeigt Margareta Mommsen, wie der schil\u00adlernde Mythos um den rus\u00adsi\u00adschen Pr\u00e4\u00adsi\u00adden\u00adten die Macht\u00adver\u00adh\u00e4lt\u00adnisse im Land ver\u00adschlei\u00adert. Tat\u00ads\u00e4ch\u00adlich wird das WM-Gast\u00adge\u00adber\u00adland von einem klan\u00addes\u00adti\u00adnen Netz\u00adwerk aus Indus\u00adtrie\u00adbos\u00adsen und Olig\u00adar\u00adchen regiert \u2013 Putins Polit\u00adb\u00fcro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/russlandverstehen.eu\\\/wp-content\\\/uploads\\\/textende.png\",\"contentUrl\":\"https:\\\/\\\/russlandverstehen.eu\\\/wp-content\\\/uploads\\\/textende.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Putins Polit\u00adb\u00fcro (1\\\/\u200b3)\"}]},{\"@type\":\"WebSite\",\"@id\":\"\\\/#website\",\"url\":\"\\\/\",\"name\":\"Russland verstehen\",\"description\":\"Zentrum Liberale Moderne\",\"publisher\":{\"@id\":\"\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"\\\/#organization\",\"name\":\"Russland verstehen\",\"url\":\"\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Russland verstehen\"},\"image\":{\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiberaleModerne\\\/\",\"https:\\\/\\\/x.com\\\/liberalemoderne\"]},{\"@type\":\"Person\",\"@id\":\"\\\/#\\\/schema\\\/person\\\/a0d0021b49707475f3a72175f498f52e\",\"name\":\"Margareta Mommsen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/wp-content\\\/uploads\\\/User-150x150.png\",\"url\":\"https:\\\/\\\/russlandverstehen.eu\\\/wp-content\\\/uploads\\\/User-150x150.png\",\"contentUrl\":\"https:\\\/\\\/russlandverstehen.eu\\\/wp-content\\\/uploads\\\/User-150x150.png\",\"caption\":\"Margareta Mommsen\"},\"description\":\"Margareta Mommsen ist emeritierte Professorin f\u00fcr Politikwissenschaft an der Ludwig-Maximilians-Universit\u00e4t M\u00fcnchen. Zuvor war sie Professorin an der Universit\u00e4t der Bundeswehr in Hamburg. Die Schwerpunkte ihrer Forschung und Lehre sind das politische System Russland und die Transformation von Autokratien in freiheitliche Ordnungen.\",\"url\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/author\\\/margareta-mommsen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Russland verstehen: Putins Polit\u00adb\u00fcro (1\/\u200b3)","description":"Im ersten Teil zeigt Margareta Mommsen, wie der schil\u00adlernde Mythos um den rus\u00adsi\u00adschen Pr\u00e4\u00adsi\u00adden\u00adten die Macht\u00adver\u00adh\u00e4lt\u00adnisse im Land ver\u00adschlei\u00adert. Tat\u00ads\u00e4ch\u00adlich wird das WM-Gast\u00adge\u00adber\u00adland von einem klan\u00addes\u00adti\u00adnen Netz\u00adwerk aus Indus\u00adtrie\u00adbos\u00adsen und Olig\u00adar\u00adchen regiert \u2013 Putins Polit\u00adb\u00fcro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/","og_locale":"de_DE","og_type":"article","og_title":"Putins Polit\u00adb\u00fcro (1\/\u200b3)","og_description":"Der schillernde Mythos um Wladimir Putin verschleiert die wahren Machtverh\u00e4ltnisse im Land.","og_url":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/","og_site_name":"Russland verstehen","article_publisher":"https:\/\/www.facebook.com\/LiberaleModerne\/","article_published_time":"2018-06-20T12:31:23+00:00","article_modified_time":"2020-03-28T01:21:13+00:00","og_image":[{"url":"https:\/\/russlandverstehen.eu\/wp-content\/uploads\/textende.png","type":"","width":"","height":""}],"author":"Margareta Mommsen","twitter_card":"summary_large_image","twitter_title":"Putins Polit\u00adb\u00fcro (1\/\u200b3)","twitter_description":"Der schillernde Mythos um Wladimir Putin verschleiert die wahren Machtverh\u00e4ltnisse im Land","twitter_creator":"@liberalemoderne","twitter_site":"@liberalemoderne","twitter_misc":{"Verfasst von":"Margareta Mommsen","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/#article","isPartOf":{"@id":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/"},"author":{"name":"Margareta Mommsen","@id":"\/#\/schema\/person\/a0d0021b49707475f3a72175f498f52e"},"headline":"Putins Polit\u00adb\u00fcro (1\/\u200b3)","datePublished":"2018-06-20T12:31:23+00:00","dateModified":"2020-03-28T01:21:13+00:00","mainEntityOfPage":{"@id":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/"},"wordCount":947,"publisher":{"@id":"\/#organization"},"image":{"@id":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/#primaryimage"},"thumbnailUrl":"https:\/\/russlandverstehen.eu\/wp-content\/uploads\/textende.png","keywords":["\u00d6stliche Nachbarschaft","Putin","Russland","WM2018"],"articleSection":["Analyse&emsp;"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/","url":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/","name":"Russland verstehen: Putins Polit\u00adb\u00fcro (1\/\u200b3)","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/#primaryimage"},"image":{"@id":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/#primaryimage"},"thumbnailUrl":"https:\/\/russlandverstehen.eu\/wp-content\/uploads\/textende.png","datePublished":"2018-06-20T12:31:23+00:00","dateModified":"2020-03-28T01:21:13+00:00","description":"Im ersten Teil zeigt Margareta Mommsen, wie der schil\u00adlernde Mythos um den rus\u00adsi\u00adschen Pr\u00e4\u00adsi\u00adden\u00adten die Macht\u00adver\u00adh\u00e4lt\u00adnisse im Land ver\u00adschlei\u00adert. Tat\u00ads\u00e4ch\u00adlich wird das WM-Gast\u00adge\u00adber\u00adland von einem klan\u00addes\u00adti\u00adnen Netz\u00adwerk aus Indus\u00adtrie\u00adbos\u00adsen und Olig\u00adar\u00adchen regiert \u2013 Putins Polit\u00adb\u00fcro.","breadcrumb":{"@id":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/#primaryimage","url":"https:\/\/russlandverstehen.eu\/wp-content\/uploads\/textende.png","contentUrl":"https:\/\/russlandverstehen.eu\/wp-content\/uploads\/textende.png"},{"@type":"BreadcrumbList","@id":"https:\/\/russlandverstehen.eu\/de\/margareta-mommsen-wm2018-russland-verstehen-putins-politbuero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/russlandverstehen.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Putins Polit\u00adb\u00fcro (1\/\u200b3)"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Russland verstehen","description":"Zentrum Liberale Moderne","publisher":{"@id":"\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"\/#organization","name":"Russland verstehen","url":"\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Russland verstehen"},"image":{"@id":"\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiberaleModerne\/","https:\/\/x.com\/liberalemoderne"]},{"@type":"Person","@id":"\/#\/schema\/person\/a0d0021b49707475f3a72175f498f52e","name":"Margareta Mommsen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/russlandverstehen.eu\/wp-content\/uploads\/User-150x150.png","url":"https:\/\/russlandverstehen.eu\/wp-content\/uploads\/User-150x150.png","contentUrl":"https:\/\/russlandverstehen.eu\/wp-content\/uploads\/User-150x150.png","caption":"Margareta Mommsen"},"description":"Margareta Mommsen ist emeritierte Professorin f\u00fcr Politikwissenschaft an der Ludwig-Maximilians-Universit\u00e4t M\u00fcnchen. Zuvor war sie Professorin an der Universit\u00e4t der Bundeswehr in Hamburg. Die Schwerpunkte ihrer Forschung und Lehre sind das politische System Russland und die Transformation von Autokratien in freiheitliche Ordnungen.","url":"https:\/\/russlandverstehen.eu\/de\/author\/margareta-mommsen\/"}]}},"jetpack_featured_media_url":"","menu_order":459,"_links":{"self":[{"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/posts\/28151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/comments?post=28151"}],"version-history":[{"count":4,"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/posts\/28151\/revisions"}],"predecessor-version":[{"id":36119,"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/posts\/28151\/revisions\/36119"}],"wp:attachment":[{"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/media?parent=28151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/categories?post=28151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/tags?post=28151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}