{"id":48,"count":35,"description":"Themenschwerpunkt","link":"https:\/\/russlandverstehen.eu\/de\/tag\/oestliche-nachbarschaft\/","name":"\u00d6stliche Nachbarschaft","slug":"oestliche-nachbarschaft","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00d6stliche Nachbarschaft Archive - Russland verstehen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/russlandverstehen.eu\/de\/tag\/oestliche-nachbarschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00d6stliche Nachbarschaft-Archiv\" \/>\n<meta property=\"og:description\" content=\"The\u00admen\u00adschwer\u00adpunkt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/russlandverstehen.eu\/de\/tag\/oestliche-nachbarschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"Russland verstehen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@liberalemoderne\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/tag\\\/oestliche-nachbarschaft\\\/\",\"url\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/tag\\\/oestliche-nachbarschaft\\\/\",\"name\":\"\u00d6stliche Nachbarschaft Archive - Russland verstehen\",\"isPartOf\":{\"@id\":\"\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/tag\\\/oestliche-nachbarschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/tag\\\/oestliche-nachbarschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/russlandverstehen.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00d6stliche Nachbarschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"\\\/#website\",\"url\":\"\\\/\",\"name\":\"Russland verstehen\",\"description\":\"Zentrum Liberale Moderne\",\"publisher\":{\"@id\":\"\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"\\\/#organization\",\"name\":\"Russland verstehen\",\"url\":\"\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Russland verstehen\"},\"image\":{\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiberaleModerne\\\/\",\"https:\\\/\\\/x.com\\\/liberalemoderne\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00d6stliche Nachbarschaft Archive - Russland verstehen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/russlandverstehen.eu\/de\/tag\/oestliche-nachbarschaft\/","og_locale":"de_DE","og_type":"article","og_title":"\u00d6stliche Nachbarschaft-Archiv","og_description":"The\u00admen\u00adschwer\u00adpunkt","og_url":"https:\/\/russlandverstehen.eu\/de\/tag\/oestliche-nachbarschaft\/","og_site_name":"Russland verstehen","twitter_card":"summary_large_image","twitter_site":"@liberalemoderne","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/russlandverstehen.eu\/de\/tag\/oestliche-nachbarschaft\/","url":"https:\/\/russlandverstehen.eu\/de\/tag\/oestliche-nachbarschaft\/","name":"\u00d6stliche Nachbarschaft Archive - Russland verstehen","isPartOf":{"@id":"\/#website"},"breadcrumb":{"@id":"https:\/\/russlandverstehen.eu\/de\/tag\/oestliche-nachbarschaft\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/russlandverstehen.eu\/de\/tag\/oestliche-nachbarschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/russlandverstehen.eu\/de\/"},{"@type":"ListItem","position":2,"name":"\u00d6stliche Nachbarschaft"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Russland verstehen","description":"Zentrum Liberale Moderne","publisher":{"@id":"\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"\/#organization","name":"Russland verstehen","url":"\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Russland verstehen"},"image":{"@id":"\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiberaleModerne\/","https:\/\/x.com\/liberalemoderne"]}]}},"_links":{"self":[{"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/tags\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/posts?tags=48"},{"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/tribe_events?tags=48"},{"href":"https:\/\/russlandverstehen.eu\/de\/wp-json\/wp\/v2\/tec_calendar_embed?tags=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}